 {"id":1287,"date":"2019-06-03T19:30:34","date_gmt":"2019-06-03T17:30:34","guid":{"rendered":"https:\/\/www.solidaridad-ev.org\/?p=1287"},"modified":"2019-10-22T21:29:42","modified_gmt":"2019-10-22T19:29:42","slug":"fotoausstellung-the-mexico-project-von-michael-willoefer","status":"publish","type":"post","link":"https:\/\/www.solidaridad-ev.org\/es\/2019\/06\/03\/fotoausstellung-the-mexico-project-von-michael-willoefer\/","title":{"rendered":"Fotoausstellung &#8220;The Mexico Project&#8221; von Michael Willoefer"},"content":{"rendered":"\n<p>The Mexico Project ist ein Langzeitprojekt, f\u00fcr das der Fotok\u00fcnstler Michael Willoefer durch den S\u00fcden und das Zentrum Mexikos reiste. Die Idee f\u00fcr das Projekt entstand in Zusammenarbeit mit dem Mexikanischen Au\u00dfenministerium und dem Museum Laboratorio Arte Alameda in Mexiko Stadt. <\/p>\n\n\n\n<p>Die Ausstellung findet im Rahmen der <a target=\"_blank\" href=\"https:\/\/www.facebook.com\/GlobaleInHalle\/\" rel=\"noreferrer noopener\">Globale in Halle<\/a> statt. Entsprechend wird am Tag der offiziellen Ausstellungser\u00f6ffnung um 20 Uhr ein Spielfilm gezeigt. Nach dem Film gibt es die Gelegenheit, mit dem K\u00fcnstler und Mitgliedern des Vereins <a target=\"_blank\" href=\"https:\/\/www.facebook.com\/solidaridad.ev\/\" rel=\"noreferrer noopener\">Solidaridad e.V.<\/a> ins Gespr\u00e4ch zu kommen. <\/p>\n\n\n\n<p>&#8220;Im Winter 2016 reiste er entlang der Pazifikk\u00fcste in ein kleines, nur \u00fcber Boot zu erreichendes, Fischerdorf im S\u00fcden des Landes, unweit der Grenze zu Guatemala. Er fragte nach einer Herberge, es gab keine. Eine \u00e4ltere Frau, die Essen verkaufte, lud ihn spontan ein, bei ihr und ihrer Familie zu bleiben. In Mexiko klingelt man nicht, man trifft die Leute auf der Stra\u00dfe. Selbst, wenn es regnet, ist es warm. Willoefer begleitete die M\u00e4nner der Familie zum Fischen, lernte andere Dorfbewohner kennen und fotografierte einige von ihnen.&#8221; (Auszug Artikel Tagesspiegel &#8220;Von Lichtenberg nach Mexiko und zur\u00fcck&#8221; <a target=\"_blank\" href=\"https:\/\/www.tagesspiegel.de\/berlin\/berliner-fotograf-von-lichtenberg-nach-mexiko-und-zurueck\/23619888.html?fbclid=IwAR39foW16eKLfc4g8ZQ8gM3vAlinbQLZ0KO9yZ8ui-CY6018G3ddcPjg55U\" rel=\"noreferrer noopener\">https:\/\/www.tagesspiegel.de\/berlin\/berliner-fotograf-von-lichtenberg-nach-mexiko-und-zurueck\/23619888.html<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Mexico Project ist ein Langzeitprojekt, f\u00fcr das der Fotok\u00fcnstler Michael Willoefer durch den S\u00fcden und das Zentrum Mexikos reiste. Die Idee f\u00fcr das Projekt entstand in Zusammenarbeit mit dem Mexikanischen Au\u00dfenministerium und dem Museum Laboratorio Arte Alameda in Mexiko Stadt. Die Ausstellung findet im Rahmen der Globale in Halle statt. Entsprechend wird am Tag &hellip; <a href=\"https:\/\/www.solidaridad-ev.org\/es\/2019\/06\/03\/fotoausstellung-the-mexico-project-von-michael-willoefer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Fotoausstellung &#8220;The Mexico Project&#8221; von Michael Willoefer&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,17],"tags":[19,33],"class_list":["post-1287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-film","category-gespraech","tag-globale-in-halle","tag-luchs-kino-halle"],"_links":{"self":[{"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/posts\/1287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/comments?post=1287"}],"version-history":[{"count":1,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/posts\/1287\/revisions"}],"predecessor-version":[{"id":1289,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/posts\/1287\/revisions\/1289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/media\/1288"}],"wp:attachment":[{"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/media?parent=1287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/categories?post=1287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solidaridad-ev.org\/es\/wp-json\/wp\/v2\/tags?post=1287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}